{"id":14658,"date":"2024-06-04T09:55:01","date_gmt":"2024-06-04T15:55:01","guid":{"rendered":"https:\/\/periodiconuevomilenio.com\/?p=14658"},"modified":"2024-06-04T09:55:03","modified_gmt":"2024-06-04T15:55:03","slug":"pepe-gonzalez-acepto-su-derrota","status":"publish","type":"post","link":"https:\/\/periodiconuevomilenio.com\/index.php\/2024\/06\/04\/pepe-gonzalez-acepto-su-derrota\/","title":{"rendered":"Pepe Gonz\u00e1lez acept\u00f3 su derrota."},"content":{"rendered":"\n<p>JARAL DEL PROGRESO, GTO.- Con toda civilidad y responsabilidad, Jos\u00e9 Gonz\u00e1lez Ojeda, alcalde con licencia y candidato a la alcald\u00eda, acepto su derrota y dijo que respetara la voluntad de la ciudadan\u00eda, ya que en esta ocasi\u00f3n los resultados no le favorecieron.<br>Dando la cara y en su perfil personal del Facebook, explic\u00f3 que la democracia trata de esto, de convocar a la ciudadan\u00eda a tomar una decisi\u00f3n, y cuando as\u00ed sucede, a respetarla y reconocer a quien se eligi\u00f3, junto con su proyecto pol\u00edtico.<br>\u201cLa tendencia de votos no nos favorece, y, por lo tanto, el proyecto ganador, habr\u00e1 de dar a Jaral del Progreso el servicio que las familias requieren y merecen.<\/p>\n\n\n\n<p>Gracias al equipo que me acompa\u00f1\u00f3 a tocar miles de hogares juntos, y al encuentro ciudadano, sincero y con propuestas factibles. El sello de la honestidad, y la experiencia probada, nos acompa\u00f1ar\u00e1n siempre.<\/p>\n\n\n\n<p>As\u00ed como en 2021 festej\u00e9 haber triunfado, hoy acepto con responsabilidad el resultado del proceso electoral\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"853\" src=\"https:\/\/periodiconuevomilenio.com\/wp-content\/uploads\/2024\/06\/440967880_122170399646018510_6022334822006802464_n-1.jpg\" alt=\"\" class=\"wp-image-14660\" srcset=\"https:\/\/periodiconuevomilenio.com\/wp-content\/uploads\/2024\/06\/440967880_122170399646018510_6022334822006802464_n-1.jpg 853w, https:\/\/periodiconuevomilenio.com\/wp-content\/uploads\/2024\/06\/440967880_122170399646018510_6022334822006802464_n-1-300x300.jpg 300w, https:\/\/periodiconuevomilenio.com\/wp-content\/uploads\/2024\/06\/440967880_122170399646018510_6022334822006802464_n-1-150x150.jpg 150w, https:\/\/periodiconuevomilenio.com\/wp-content\/uploads\/2024\/06\/440967880_122170399646018510_6022334822006802464_n-1-768x768.jpg 768w, https:\/\/periodiconuevomilenio.com\/wp-content\/uploads\/2024\/06\/440967880_122170399646018510_6022334822006802464_n-1-350x350.jpg 350w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>JARAL DEL PROGRESO, GTO.- Con toda civilidad y responsabilidad, Jos\u00e9 Gonz\u00e1lez Ojeda, alcalde con licencia y candidato a<\/p>\n","protected":false},"author":1,"featured_media":14660,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[34],"tags":[23],"class_list":["post-14658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jaral-del-progreso","tag-jaral"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/periodiconuevomilenio.com\/wp-content\/uploads\/2024\/06\/440967880_122170399646018510_6022334822006802464_n-1.jpg","_links":{"self":[{"href":"https:\/\/periodiconuevomilenio.com\/index.php\/wp-json\/wp\/v2\/posts\/14658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/periodiconuevomilenio.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/periodiconuevomilenio.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/periodiconuevomilenio.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/periodiconuevomilenio.com\/index.php\/wp-json\/wp\/v2\/comments?post=14658"}],"version-history":[{"count":1,"href":"https:\/\/periodiconuevomilenio.com\/index.php\/wp-json\/wp\/v2\/posts\/14658\/revisions"}],"predecessor-version":[{"id":14661,"href":"https:\/\/periodiconuevomilenio.com\/index.php\/wp-json\/wp\/v2\/posts\/14658\/revisions\/14661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/periodiconuevomilenio.com\/index.php\/wp-json\/wp\/v2\/media\/14660"}],"wp:attachment":[{"href":"https:\/\/periodiconuevomilenio.com\/index.php\/wp-json\/wp\/v2\/media?parent=14658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/periodiconuevomilenio.com\/index.php\/wp-json\/wp\/v2\/categories?post=14658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/periodiconuevomilenio.com\/index.php\/wp-json\/wp\/v2\/tags?post=14658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}